{"id":850,"date":"2024-08-19T13:13:28","date_gmt":"2024-08-19T13:13:28","guid":{"rendered":"https:\/\/tennis.egoprogetti.ch\/?page_id=850"},"modified":"2026-07-08T12:34:47","modified_gmt":"2026-07-08T12:34:47","slug":"campus-estivo","status":"publish","type":"page","link":"https:\/\/tennisgordola.ch\/index.php\/campus-estivo\/","title":{"rendered":"Campus estivo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"850\" class=\"elementor elementor-850\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0089ab3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0089ab3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e9865e\" data-id=\"2e9865e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca882a elementor-widget elementor-widget-spacer\" data-id=\"3ca882a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fe6656 elementor-widget elementor-widget-image\" data-id=\"3fe6656\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"726\" height=\"1024\" src=\"https:\/\/tennisgordola.ch\/wp-content\/uploads\/2026\/01\/volantino_corsiestivibimbi_2026-726x1024.jpg\" class=\"attachment-large size-large wp-image-3738\" alt=\"\" srcset=\"https:\/\/tennisgordola.ch\/wp-content\/uploads\/2026\/01\/volantino_corsiestivibimbi_2026-726x1024.jpg 726w, https:\/\/tennisgordola.ch\/wp-content\/uploads\/2026\/01\/volantino_corsiestivibimbi_2026-213x300.jpg 213w, https:\/\/tennisgordola.ch\/wp-content\/uploads\/2026\/01\/volantino_corsiestivibimbi_2026-768x1083.jpg 768w, https:\/\/tennisgordola.ch\/wp-content\/uploads\/2026\/01\/volantino_corsiestivibimbi_2026.jpg 842w\" sizes=\"(max-width: 726px) 100vw, 726px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c2b704 elementor-widget elementor-widget-spacer\" data-id=\"0c2b704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-863416f elementor-widget elementor-widget-text-editor\" data-id=\"863416f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Anche quest&#8217;anno proponiamo durante il periodo estivo dei campus di Kids tennis, a partire dai 5 anni di et\u00e0.<br \/>I Campus si svolgono da luned\u00ec a venerd\u00ec, dalle 09:00 alle 12:00.<br \/>Giornalmente giochiamo 1 ora a tennis, avremo poi 1 ora di svago in cui i bambini saranno occupati a fare colazione, svolgere una caccia al tesoro o fare dei giochi con l&#8217;acqua, ecc. per poi concludere ancora con 1 ora di tennis. L&#8217;ultimo giorno, il venerd\u00ec, pizza per tutti!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e85e3fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e85e3fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb7a97d\" data-id=\"eb7a97d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff6a9ce elementor-widget elementor-widget-wpforms\" data-id=\"ff6a9ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-1129\"><form id=\"wpforms-form-1129\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1129\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/850\" data-token=\"defec93ee5c499aee09fcd888f034615\" data-token-time=\"1788332509\"><noscript class=\"wpforms-error-noscript\">Abilita JavaScript nel browser per completare questo modulo.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Abilita JavaScript nel browser per completare questo modulo.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-1129-field_36-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"36\"><label class=\"wpforms-field-label\" for=\"wpforms-1129-field_36\">Nome Genitore <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1129-field_36\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][36]\" aria-errormessage=\"wpforms-1129-field_36-error\" required><\/div>\t\t<div id=\"wpforms-1129-field_2-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"2\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-1129-field_2\" >se alle i<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-1129-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-1129-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nome  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-1129-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-1129-field_1-error\" required><label for=\"wpforms-1129-field_1\" class=\"wpforms-field-sublabel after\">Nome<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-1129-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-1129-field_1-last-error\" required><label for=\"wpforms-1129-field_1-last\" class=\"wpforms-field-sublabel after\">Cognome<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-1129-field_4-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"4\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-33-33\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-1129-field_26-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-1129-field_26\">Indirizzo<\/label><input type=\"text\" id=\"wpforms-1129-field_26\" class=\"wpforms-field-medium\" name=\"wpforms[fields][26]\" aria-errormessage=\"wpforms-1129-field_26-error\" ><\/div><div id=\"wpforms-1129-field_31-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"31\"><fieldset><legend class=\"wpforms-field-label\">Data di nascita<\/legend><div class=\"wpforms-field-date-dropdown-wrap wpforms-field-medium\"><select name=\"wpforms[fields][31][date][d]\" id=\"wpforms-1129-field_31-day\" class=\"wpforms-field-date-time-date-day\" aria-label=\"Giorno\" ><option value=\"\" class=\"placeholder\" selected disabled>GG<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><option value=\"13\" >13<\/option><option value=\"14\" >14<\/option><option value=\"15\" >15<\/option><option value=\"16\" >16<\/option><option value=\"17\" >17<\/option><option value=\"18\" >18<\/option><option value=\"19\" >19<\/option><option value=\"20\" >20<\/option><option value=\"21\" >21<\/option><option value=\"22\" >22<\/option><option value=\"23\" >23<\/option><option value=\"24\" >24<\/option><option value=\"25\" >25<\/option><option value=\"26\" >26<\/option><option value=\"27\" >27<\/option><option value=\"28\" >28<\/option><option value=\"29\" >29<\/option><option value=\"30\" >30<\/option><option value=\"31\" >31<\/option><\/select><select name=\"wpforms[fields][31][date][m]\" id=\"wpforms-1129-field_31-month\" class=\"wpforms-field-date-time-date-month\" aria-label=\"Mese\" ><option value=\"\" class=\"placeholder\" selected disabled>MM<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><\/select><select name=\"wpforms[fields][31][date][y]\" id=\"wpforms-1129-field_31-year\" class=\"wpforms-field-date-time-date-year\" aria-label=\"Anno\" ><option value=\"\" class=\"placeholder\" selected disabled>AAAA<\/option><option value=\"2027\" >2027<\/option><option value=\"2026\" >2026<\/option><option value=\"2025\" >2025<\/option><option value=\"2024\" >2024<\/option><option value=\"2023\" >2023<\/option><option value=\"2022\" >2022<\/option><option value=\"2021\" >2021<\/option><option value=\"2020\" >2020<\/option><option value=\"2019\" >2019<\/option><option value=\"2018\" >2018<\/option><option value=\"2017\" >2017<\/option><option value=\"2016\" >2016<\/option><option value=\"2015\" >2015<\/option><option value=\"2014\" >2014<\/option><option value=\"2013\" >2013<\/option><option value=\"2012\" >2012<\/option><option value=\"2011\" >2011<\/option><option value=\"2010\" >2010<\/option><option value=\"2009\" >2009<\/option><option value=\"2008\" >2008<\/option><option value=\"2007\" >2007<\/option><option value=\"2006\" >2006<\/option><option value=\"2005\" >2005<\/option><option value=\"2004\" >2004<\/option><option value=\"2003\" >2003<\/option><option value=\"2002\" >2002<\/option><option value=\"2001\" >2001<\/option><option value=\"2000\" >2000<\/option><option value=\"1999\" >1999<\/option><option value=\"1998\" >1998<\/option><option value=\"1997\" >1997<\/option><option value=\"1996\" >1996<\/option><option value=\"1995\" >1995<\/option><option value=\"1994\" >1994<\/option><option value=\"1993\" >1993<\/option><option value=\"1992\" >1992<\/option><option value=\"1991\" >1991<\/option><option value=\"1990\" >1990<\/option><option value=\"1989\" >1989<\/option><option value=\"1988\" >1988<\/option><option value=\"1987\" >1987<\/option><option value=\"1986\" >1986<\/option><option value=\"1985\" >1985<\/option><option value=\"1984\" >1984<\/option><option value=\"1983\" >1983<\/option><option value=\"1982\" >1982<\/option><option value=\"1981\" >1981<\/option><option value=\"1980\" >1980<\/option><option value=\"1979\" >1979<\/option><option value=\"1978\" >1978<\/option><option value=\"1977\" >1977<\/option><option value=\"1976\" >1976<\/option><option value=\"1975\" >1975<\/option><option value=\"1974\" >1974<\/option><option value=\"1973\" >1973<\/option><option value=\"1972\" >1972<\/option><option value=\"1971\" >1971<\/option><option value=\"1970\" >1970<\/option><option value=\"1969\" >1969<\/option><option value=\"1968\" >1968<\/option><option value=\"1967\" >1967<\/option><option value=\"1966\" >1966<\/option><option value=\"1965\" >1965<\/option><option value=\"1964\" >1964<\/option><option value=\"1963\" >1963<\/option><option value=\"1962\" >1962<\/option><option value=\"1961\" >1961<\/option><option value=\"1960\" >1960<\/option><option value=\"1959\" >1959<\/option><option value=\"1958\" >1958<\/option><option value=\"1957\" >1957<\/option><option value=\"1956\" >1956<\/option><option value=\"1955\" >1955<\/option><option value=\"1954\" >1954<\/option><option value=\"1953\" >1953<\/option><option value=\"1952\" >1952<\/option><option value=\"1951\" >1951<\/option><option value=\"1950\" >1950<\/option><option value=\"1949\" >1949<\/option><option value=\"1948\" >1948<\/option><option value=\"1947\" >1947<\/option><option value=\"1946\" >1946<\/option><option value=\"1945\" >1945<\/option><option value=\"1944\" >1944<\/option><option value=\"1943\" >1943<\/option><option value=\"1942\" >1942<\/option><option value=\"1941\" >1941<\/option><option value=\"1940\" >1940<\/option><option value=\"1939\" >1939<\/option><option value=\"1938\" >1938<\/option><option value=\"1937\" >1937<\/option><option value=\"1936\" >1936<\/option><option value=\"1935\" >1935<\/option><option value=\"1934\" >1934<\/option><option value=\"1933\" >1933<\/option><option value=\"1932\" >1932<\/option><option value=\"1931\" >1931<\/option><option value=\"1930\" >1930<\/option><option value=\"1929\" >1929<\/option><option value=\"1928\" >1928<\/option><option value=\"1927\" >1927<\/option><option value=\"1926\" >1926<\/option><option value=\"1925\" >1925<\/option><option value=\"1924\" >1924<\/option><option value=\"1923\" >1923<\/option><option value=\"1922\" >1922<\/option><option value=\"1921\" >1921<\/option><option value=\"1920\" >1920<\/option><\/select><\/div><\/fieldset><\/div><div id=\"wpforms-1129-field_34-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"34\"><label class=\"wpforms-field-label\" for=\"wpforms-1129-field_34\">Esperienza tennistica<\/label><select id=\"wpforms-1129-field_34\" class=\"wpforms-field-medium\" name=\"wpforms[fields][34]\"><option value=\"Non ho mai giocato a tennis\"  class=\"choice-1 depth-1\"  >Non ho mai giocato a tennis<\/option><option value=\"Ho giocato a tennis\"  class=\"choice-2 depth-1\"  >Ho giocato a tennis<\/option><option value=\"Ho frequentato il corso del 2024\/2025\"  class=\"choice-3 depth-1\"  >Ho frequentato il corso del 2024\/2025<\/option><option value=\"Ho frequentato il campus 2025\"  class=\"choice-4 depth-1\"  >Ho frequentato il campus 2025<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-1129-field_27-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"27\"><label class=\"wpforms-field-label\" for=\"wpforms-1129-field_27\">CAP e Citt\u00e0<\/label><input type=\"text\" id=\"wpforms-1129-field_27\" class=\"wpforms-field-medium\" name=\"wpforms[fields][27]\" aria-errormessage=\"wpforms-1129-field_27-error\" ><\/div><div id=\"wpforms-1129-field_32-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"32\"><label class=\"wpforms-field-label\" for=\"wpforms-1129-field_32\">Numero AVS <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1129-field_32\" class=\"wpforms-field-medium wpforms-field-required wpforms-limit-characters-enabled\" data-form-id=\"1129\" data-field-id=\"32\" data-text-limit=\"14\" name=\"wpforms[fields][32]\" placeholder=\"XXX.XX.XXX.XXX\" aria-errormessage=\"wpforms-1129-field_32-error\" maxlength=\"14\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-1129-field_29-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"29\"><label class=\"wpforms-field-label\" for=\"wpforms-1129-field_29\">Telefono genitore <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-1129-field_29\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][29]\" aria-label=\"Telefono genitore\" aria-errormessage=\"wpforms-1129-field_29-error\" required><\/div><div id=\"wpforms-1129-field_33-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"33\"><label class=\"wpforms-field-label\" for=\"wpforms-1129-field_33\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1129-field_33\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][33]\" spellcheck=\"false\" aria-errormessage=\"wpforms-1129-field_33-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-1129-field_45-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-3-columns\" data-field-type=\"checkbox\" data-field-id=\"45\"><fieldset><legend class=\"wpforms-field-label\">Iscrizione al Campus alle seguenti date ( sono possibili scelte multiple )<\/legend><ul id=\"wpforms-1129-field_45\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1129-field_45_1\" name=\"wpforms[fields][45][]\" value=\"1\u00b0 Corso 06 -10 Luglio 2026\" aria-errormessage=\"wpforms-1129-field_45_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_45_1\">1\u00b0 Corso 06 -10 Luglio 2026<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-1129-field_45_2\" name=\"wpforms[fields][45][]\" value=\"2\u00b0 Corso 27 -31 Luglio 2026\" aria-errormessage=\"wpforms-1129-field_45_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_45_2\">2\u00b0 Corso 27 -31 Luglio 2026<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-1129-field_45_3\" name=\"wpforms[fields][45][]\" value=\"3\u00b0 Corso 17 - 21 Agosto 2026 (solo 2 iscrizioni disponibili )\" aria-errormessage=\"wpforms-1129-field_45_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_45_3\">3\u00b0 Corso 17 - 21 Agosto 2026 (solo 2 iscrizioni disponibili )<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-1129-field_37-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-type=\"radio\" data-field-id=\"37\"><fieldset><legend class=\"wpforms-field-label\">Facci sapere come sei arrivata\/o al Tennis di Gordola<\/legend><ul id=\"wpforms-1129-field_37\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-1129-field_37_1\" name=\"wpforms[fields][37]\" value=\"da conoscenti \/ amici\" aria-errormessage=\"wpforms-1129-field_37_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_37_1\">da conoscenti \/ amici<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-1129-field_37_2\" name=\"wpforms[fields][37]\" value=\"dalla pagina internet tennisgordola.ch\" aria-errormessage=\"wpforms-1129-field_37_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_37_2\">dalla pagina internet tennisgordola.ch<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-1129-field_37_3\" name=\"wpforms[fields][37]\" value=\"dai social media - Instagram, Facebook\" aria-errormessage=\"wpforms-1129-field_37_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_37_3\">dai social media - Instagram, Facebook<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-1129-field_37_4\" name=\"wpforms[fields][37]\" value=\"ho visto i volantini al Bar Bistro\" aria-errormessage=\"wpforms-1129-field_37_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_37_4\">ho visto i volantini al Bar Bistro<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-1129-field_37_5\" name=\"wpforms[fields][37]\" value=\"dal sito ticinoperbambini.ch\" aria-errormessage=\"wpforms-1129-field_37_5-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_37_5\">dal sito ticinoperbambini.ch<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-1129-field_37_6\" name=\"wpforms[fields][37]\" value=\"altro\" aria-errormessage=\"wpforms-1129-field_37_6-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_37_6\">altro<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-1129-field_43-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"43\"><fieldset><legend class=\"wpforms-field-label\">Durante i campus verranno scattate delle foto per marketing del tennis, notificate se non date il consenso.<\/legend><ul id=\"wpforms-1129-field_43\"><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-1129-field_43_2\" name=\"wpforms[fields][43][]\" value=\"Non do consenso\" aria-errormessage=\"wpforms-1129-field_43_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1129-field_43_2\">Non do consenso<\/label><\/li><\/ul><\/fieldset><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-1129-field_2-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-1129-field_2-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-1129-field_2-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1129\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/pages\/850\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1129\" class=\"wpforms-submit\" data-alt-text=\"Invio in corso...\" data-submit-text=\"Invia\" aria-live=\"assertive\" value=\"wpforms-submit\">Invia<\/button><img decoding=\"async\" src=\"https:\/\/tennisgordola.ch\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Caricamento\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49671e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49671e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-855a610\" data-id=\"855a610\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-153648f elementor-widget elementor-widget-image\" data-id=\"153648f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"631\" height=\"601\" src=\"https:\/\/tennisgordola.ch\/wp-content\/uploads\/2026\/01\/gruppo-2025.png\" class=\"attachment-large size-large wp-image-3742\" alt=\"\" srcset=\"https:\/\/tennisgordola.ch\/wp-content\/uploads\/2026\/01\/gruppo-2025.png 631w, https:\/\/tennisgordola.ch\/wp-content\/uploads\/2026\/01\/gruppo-2025-300x286.png 300w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b9c51d elementor-widget elementor-widget-spacer\" data-id=\"1b9c51d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5190de9 elementor-widget elementor-widget-spacer\" data-id=\"5190de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36fe121 elementor-widget elementor-widget-heading\" data-id=\"36fe121\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aiutaci a migliorare compila il modulo di soddisfazione<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0301d5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0301d5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cf3c88\" data-id=\"6cf3c88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fccf46 elementor-widget elementor-widget-text-editor\" data-id=\"0fccf46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><style id=\"wpforms-css-vars-4542\">\n\t\t\t\t#wpforms-4542 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-4542\"><form id=\"wpforms-form-4542\" class=\"wpforms-validate wpforms-form\" data-formid=\"4542\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/850\" data-token=\"837352a05e22dea8f20b4f638f7de52f\" data-token-time=\"1788332509\"><noscript class=\"wpforms-error-noscript\">Abilita JavaScript nel browser per completare questo modulo.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Abilita JavaScript nel browser per completare questo modulo.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-4542-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nome e cognome (genitore\/tutore)<\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-4542-field_1\" class=\"wpforms-field-name-first\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-4542-field_1-error\" ><label for=\"wpforms-4542-field_1\" class=\"wpforms-field-sublabel after\">Nome<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-4542-field_1-last\" class=\"wpforms-field-name-last\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-4542-field_1-last-error\" ><label for=\"wpforms-4542-field_1-last\" class=\"wpforms-field-sublabel after\">Cognome<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-4542-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-4542-field_2\">Email (genitore\/tutore)<\/label><input type=\"email\" id=\"wpforms-4542-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-4542-field_2-error\" ><\/div><div id=\"wpforms-4542-field_3-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-4542-field_3\">Telefono (genitore\/tutore)<\/label><input type=\"tel\" id=\"wpforms-4542-field_3\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][3]\" aria-label=\"Telefono (genitore\/tutore)\" aria-errormessage=\"wpforms-4542-field_3-error\" ><\/div><div id=\"wpforms-4542-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-4542-field_4\">Nome dell\u2019allievo\/a<\/label><input type=\"text\" id=\"wpforms-4542-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-4542-field_4-error\" ><\/div><div id=\"wpforms-4542-field_5-container\" class=\"wpforms-field wpforms-field-number\" data-field-type=\"number\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-4542-field_5\">Et\u00e0 dell\u2019allievo\/a<\/label><input type=\"number\" id=\"wpforms-4542-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" step=\"any\" aria-errormessage=\"wpforms-4542-field_5-error\" ><\/div><div id=\"wpforms-4542-field_6-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-4542-field_6\">date del campus<\/label><select id=\"wpforms-4542-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\"><option value=\"1\u00b0 Campus  6 - 10 Luglio\"  class=\"choice-1 depth-1\"  >1\u00b0 Campus  6 &#8211; 10 Luglio<\/option><option value=\"2\u00b0 Campus  27 - 31 Luglio\"  class=\"choice-2 depth-1\"  >2\u00b0 Campus  27 &#8211; 31 Luglio<\/option><option value=\"3\u00b0 Campus  17 - 21 Agosto\"  class=\"choice-3 depth-1\"  >3\u00b0 Campus  17 &#8211; 21 Agosto<\/option><\/select><\/div>\t\t<div id=\"wpforms-4542-field_7-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"7\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-4542-field_7\" >svolgimento di bambino\/a?<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-4542-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-4542-field_8-container\" class=\"wpforms-field wpforms-field-rating\" data-field-type=\"rating\" data-field-id=\"8\"><label class=\"wpforms-field-label\">Soddisfazione complessiva del corso<\/label><div class=\"wpforms-field-rating-wrapper wpforms-field-rating-labels-position-below\"><div class=\"wpforms-field-rating-items\"><label class=\"wpforms-field-rating-item choice-1\" for=\"wpforms-4542-field_8_1\"><span class=\"wpforms-screen-reader-element\">Valuta 1 su 5<\/span><input type=\"radio\" id=\"wpforms-4542-field_8_1\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][8]\" value=\"1\" aria-errormessage=\"wpforms-4542-field_8-error\" ><svg width=\"24\" height=\"24\" style=\"height:24px;width:24px;\" fill=\"currentColor\" color=\"#066aab\" viewBox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M1728 647q0 22-26 48l-363 354 86 500q1 7 1 20 0 21-10.5 35.5t-30.5 14.5q-19 0-40-12l-449-236-449 236q-22 12-40 12-21 0-31.5-14.5t-10.5-35.5q0-6 2-20l86-500-364-354q-25-27-25-48 0-37 56-46l502-73 225-455q19-41 49-41t49 41l225 455 502 73q56 9 56 46z\"\/><\/svg><\/label><label class=\"wpforms-field-rating-item choice-2\" for=\"wpforms-4542-field_8_2\"><span class=\"wpforms-screen-reader-element\">Valuta 2 su 5<\/span><input type=\"radio\" id=\"wpforms-4542-field_8_2\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][8]\" value=\"2\" aria-errormessage=\"wpforms-4542-field_8-error\" ><svg width=\"24\" height=\"24\" style=\"height:24px;width:24px;\" fill=\"currentColor\" color=\"#066aab\" viewBox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M1728 647q0 22-26 48l-363 354 86 500q1 7 1 20 0 21-10.5 35.5t-30.5 14.5q-19 0-40-12l-449-236-449 236q-22 12-40 12-21 0-31.5-14.5t-10.5-35.5q0-6 2-20l86-500-364-354q-25-27-25-48 0-37 56-46l502-73 225-455q19-41 49-41t49 41l225 455 502 73q56 9 56 46z\"\/><\/svg><\/label><label class=\"wpforms-field-rating-item choice-3\" for=\"wpforms-4542-field_8_3\"><span class=\"wpforms-screen-reader-element\">Valuta 3 su 5<\/span><input type=\"radio\" id=\"wpforms-4542-field_8_3\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][8]\" value=\"3\" aria-errormessage=\"wpforms-4542-field_8-error\" ><svg width=\"24\" height=\"24\" style=\"height:24px;width:24px;\" fill=\"currentColor\" color=\"#066aab\" viewBox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M1728 647q0 22-26 48l-363 354 86 500q1 7 1 20 0 21-10.5 35.5t-30.5 14.5q-19 0-40-12l-449-236-449 236q-22 12-40 12-21 0-31.5-14.5t-10.5-35.5q0-6 2-20l86-500-364-354q-25-27-25-48 0-37 56-46l502-73 225-455q19-41 49-41t49 41l225 455 502 73q56 9 56 46z\"\/><\/svg><\/label><label class=\"wpforms-field-rating-item choice-4\" for=\"wpforms-4542-field_8_4\"><span class=\"wpforms-screen-reader-element\">Valuta 4 su 5<\/span><input type=\"radio\" id=\"wpforms-4542-field_8_4\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][8]\" value=\"4\" aria-errormessage=\"wpforms-4542-field_8-error\" ><svg width=\"24\" height=\"24\" style=\"height:24px;width:24px;\" fill=\"currentColor\" color=\"#066aab\" viewBox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M1728 647q0 22-26 48l-363 354 86 500q1 7 1 20 0 21-10.5 35.5t-30.5 14.5q-19 0-40-12l-449-236-449 236q-22 12-40 12-21 0-31.5-14.5t-10.5-35.5q0-6 2-20l86-500-364-354q-25-27-25-48 0-37 56-46l502-73 225-455q19-41 49-41t49 41l225 455 502 73q56 9 56 46z\"\/><\/svg><\/label><label class=\"wpforms-field-rating-item choice-5\" for=\"wpforms-4542-field_8_5\"><span class=\"wpforms-screen-reader-element\">Valuta 5 su 5<\/span><input type=\"radio\" id=\"wpforms-4542-field_8_5\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][8]\" value=\"5\" aria-errormessage=\"wpforms-4542-field_8-error\" ><svg width=\"24\" height=\"24\" style=\"height:24px;width:24px;\" fill=\"currentColor\" color=\"#066aab\" viewBox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M1728 647q0 22-26 48l-363 354 86 500q1 7 1 20 0 21-10.5 35.5t-30.5 14.5q-19 0-40-12l-449-236-449 236q-22 12-40 12-21 0-31.5-14.5t-10.5-35.5q0-6 2-20l86-500-364-354q-25-27-25-48 0-37 56-46l502-73 225-455q19-41 49-41t49 41l225 455 502 73q56 9 56 46z\"\/><\/svg><\/label><\/div><\/div><\/div><div id=\"wpforms-4542-field_16-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Competenza e svolgimento dei maestri<\/legend><ul id=\"wpforms-4542-field_16\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_16_1\" name=\"wpforms[fields][16][]\" value=\"Non soddisfatto\" aria-errormessage=\"wpforms-4542-field_16_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_16_1\">Non soddisfatto<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_16_7\" name=\"wpforms[fields][16][]\" value=\"Abbastanza soddisfatto\" aria-errormessage=\"wpforms-4542-field_16_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_16_7\">Abbastanza soddisfatto<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_16_2\" name=\"wpforms[fields][16][]\" value=\"Soddisfatto\" aria-errormessage=\"wpforms-4542-field_16_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_16_2\">Soddisfatto<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_16_6\" name=\"wpforms[fields][16][]\" value=\"Molto soddisfatto\" aria-errormessage=\"wpforms-4542-field_16_6-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_16_6\">Molto soddisfatto<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-4542-field_17-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"17\"><fieldset><legend class=\"wpforms-field-label\">Progressi tecnici dell&#039;allievo\/a<\/legend><ul id=\"wpforms-4542-field_17\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_17_1\" name=\"wpforms[fields][17][]\" value=\"Non soddisfatto\" aria-errormessage=\"wpforms-4542-field_17_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_17_1\">Non soddisfatto<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_17_4\" name=\"wpforms[fields][17][]\" value=\"Abbastanza soddisfatto\" aria-errormessage=\"wpforms-4542-field_17_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_17_4\">Abbastanza soddisfatto<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_17_2\" name=\"wpforms[fields][17][]\" value=\"Soddisfatto\" aria-errormessage=\"wpforms-4542-field_17_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_17_2\">Soddisfatto<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_17_3\" name=\"wpforms[fields][17][]\" value=\"Molto soddisfatto\" aria-errormessage=\"wpforms-4542-field_17_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_17_3\">Molto soddisfatto<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-4542-field_18-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"18\"><fieldset><legend class=\"wpforms-field-label\">Organizzazione orari e comunicazioni<\/legend><ul id=\"wpforms-4542-field_18\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_18_1\" name=\"wpforms[fields][18][]\" value=\"Non soddisfatto\" aria-errormessage=\"wpforms-4542-field_18_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_18_1\">Non soddisfatto<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_18_4\" name=\"wpforms[fields][18][]\" value=\"Abbastanza soddisfatto\" aria-errormessage=\"wpforms-4542-field_18_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_18_4\">Abbastanza soddisfatto<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_18_2\" name=\"wpforms[fields][18][]\" value=\"Soddisfatto\" aria-errormessage=\"wpforms-4542-field_18_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_18_2\">Soddisfatto<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_18_3\" name=\"wpforms[fields][18][]\" value=\"Molto soddisfatto\" aria-errormessage=\"wpforms-4542-field_18_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_18_3\">Molto soddisfatto<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-4542-field_19-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"19\"><fieldset><legend class=\"wpforms-field-label\">Qualit\u00e0 delle strutture ed attrezzature<\/legend><ul id=\"wpforms-4542-field_19\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_19_1\" name=\"wpforms[fields][19][]\" value=\"Non soddisfatto\" aria-errormessage=\"wpforms-4542-field_19_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_19_1\">Non soddisfatto<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_19_4\" name=\"wpforms[fields][19][]\" value=\"Abbastanza soddisfatto\" aria-errormessage=\"wpforms-4542-field_19_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_19_4\">Abbastanza soddisfatto<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_19_2\" name=\"wpforms[fields][19][]\" value=\"Soddisfatto\" aria-errormessage=\"wpforms-4542-field_19_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_19_2\">Soddisfatto<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_19_3\" name=\"wpforms[fields][19][]\" value=\"Molto soddisfatto\" aria-errormessage=\"wpforms-4542-field_19_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_19_3\">Molto soddisfatto<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-4542-field_20-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"20\"><fieldset><legend class=\"wpforms-field-label\">Sicurezza in campo e gestione gruppo<\/legend><ul id=\"wpforms-4542-field_20\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_20_1\" name=\"wpforms[fields][20][]\" value=\"Non soddisfatto\" aria-errormessage=\"wpforms-4542-field_20_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_20_1\">Non soddisfatto<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_20_4\" name=\"wpforms[fields][20][]\" value=\"Abbastanza soddisfatto\" aria-errormessage=\"wpforms-4542-field_20_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_20_4\">Abbastanza soddisfatto<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_20_2\" name=\"wpforms[fields][20][]\" value=\"Soddisfatto\" aria-errormessage=\"wpforms-4542-field_20_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_20_2\">Soddisfatto<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4542-field_20_3\" name=\"wpforms[fields][20][]\" value=\"Molto soddisfatto\" aria-errormessage=\"wpforms-4542-field_20_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_20_3\">Molto soddisfatto<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-4542-field_10-container\" class=\"wpforms-field wpforms-field-radio\" data-field-type=\"radio\" data-field-id=\"10\"><fieldset><legend class=\"wpforms-field-label\">Il corso \u00e8 adeguato all\u2019et\u00e0 e al livello del bambino\/a?<\/legend><ul id=\"wpforms-4542-field_10\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-4542-field_10_1\" name=\"wpforms[fields][10]\" value=\"S\u00ec\" aria-errormessage=\"wpforms-4542-field_10_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_10_1\">S\u00ec<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-4542-field_10_2\" name=\"wpforms[fields][10]\" value=\"Parzialmente\" aria-errormessage=\"wpforms-4542-field_10_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_10_2\">Parzialmente<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-4542-field_10_3\" name=\"wpforms[fields][10]\" value=\"No\" aria-errormessage=\"wpforms-4542-field_10_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4542-field_10_3\">No<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-4542-field_12-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-4542-field_12\">Cosa ti \u00e8 piaciuto di pi\u00f9 del corso?<\/label><textarea id=\"wpforms-4542-field_12\" class=\"wpforms-field-medium\" name=\"wpforms[fields][12]\" aria-errormessage=\"wpforms-4542-field_12-error\" ><\/textarea><\/div><div id=\"wpforms-4542-field_13-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-4542-field_13\">Cosa possiamo migliorare?<\/label><textarea id=\"wpforms-4542-field_13\" class=\"wpforms-field-medium\" name=\"wpforms[fields][13]\" aria-errormessage=\"wpforms-4542-field_13-error\" ><\/textarea><\/div><div id=\"wpforms-4542-field_15-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-4542-field_15\">Note aggiuntive (facoltative)<\/label><textarea id=\"wpforms-4542-field_15\" class=\"wpforms-field-medium\" name=\"wpforms[fields][15]\" aria-errormessage=\"wpforms-4542-field_15-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-1129-field_2-container,#wpforms-4542-field_7-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-1129-field_2-container,#wpforms-4542-field_7-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-1129-field_2-container,#wpforms-4542-field_7-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"4542\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/pages\/850\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-4542\" class=\"wpforms-submit\" data-alt-text=\"Invio in corso...\" data-submit-text=\"Invia\" aria-live=\"assertive\" value=\"wpforms-submit\">Invia<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c7be4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c7be4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e28e969\" data-id=\"e28e969\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43924ad elementor-widget elementor-widget-spacer\" data-id=\"43924ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Anche quest&#8217;anno proponiamo durante il periodo estivo dei campus di Kids tennis, a partire dai 5 anni di et\u00e0.I Campus si svolgono da luned\u00ec a venerd\u00ec, dalle 09:00 alle 12:00.Giornalmente giochiamo 1 ora a tennis, avremo poi 1 ora di svago in cui i bambini saranno occupati a fare colazione, svolgere una caccia al tesoro&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-850","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/pages\/850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/comments?post=850"}],"version-history":[{"count":58,"href":"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/pages\/850\/revisions"}],"predecessor-version":[{"id":4554,"href":"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/pages\/850\/revisions\/4554"}],"wp:attachment":[{"href":"https:\/\/tennisgordola.ch\/index.php\/wp-json\/wp\/v2\/media?parent=850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}